{"id":2994,"date":"2021-11-23T16:01:23","date_gmt":"2021-11-23T16:01:23","guid":{"rendered":"https:\/\/www.audacia.co\/?p=2994"},"modified":"2024-10-22T13:29:22","modified_gmt":"2024-10-22T13:29:22","slug":"integration-dune-structure-rh-au-sein-dun-groupe-un-systeme-systemique","status":"publish","type":"post","link":"https:\/\/www.audacia.co\/fr\/blog\/integration-dune-structure-rh-au-sein-dun-groupe-un-systeme-systemique\/","title":{"rendered":"Int\u00e9gration d\u2019une structure RH au sein d\u2019un groupe: un syst\u00e8me syst\u00e9mique"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Dans le cadre du d\u00e9veloppement et de la croissance d\u2019<span style=\"text-decoration: underline;\"><span style=\"color: #3a1def; text-decoration: underline;\"><a style=\"color: #3a1def; text-decoration: underline;\" href=\"https:\/\/www.audacia.co\/fr\/blog\/audacia-un-groupe-a-la-presence-et-aux-ambitions-internationales\/\" target=\"_blank\" rel=\"noopener\">Audacia Group<\/a><\/span><\/span>, ma principale mission consistait \u00e0 mettre en place et int\u00e9grer une structure Ressources Humaines commune pour la soci\u00e9t\u00e9 m\u00e8re et ses entreprises. Quel challenge! Il n\u2019y a pas de r\u00e8gle sp\u00e9cifique \u00e0 propos de \u201cquand?\u201d et \u201cpourquoi?\u201d mettre sur pied une structure RH au sein d\u2019une organisation. <span style=\"text-decoration: underline;\"><span style=\"color: #3a1def; text-decoration: underline;\"><a style=\"color: #3a1def; text-decoration: underline;\" href=\"https:\/\/www.audacia.co\/fr\/blog\/alexandre-bonvin-laudace-de-realiser-le-plein-potentiel-de-son-entreprise\/\" target=\"_blank\" rel=\"noopener\">L\u2019acquisition de soci\u00e9t\u00e9s<\/a><\/span><\/span> disposant de leur propre ind\u00e9pendance administrative peut se r\u00e9v\u00e9ler \u00eatre une raison qui favorise cette prise de d\u00e9cision. Et c\u2019est pr\u00e9cis\u00e9ment le cas de figure auquel j\u2019ai \u00e9t\u00e9 confront\u00e9 \u00e0 mon arriv\u00e9e chez Audacia.<br \/>\nD\u2019autres facteurs peuvent \u00e9galement favoriser l\u2019int\u00e9gration d\u2019un secteur RH au sein d\u2019une entreprise. Pensons notamment \u00e0 l\u2019augmentation du nombre de salari\u00e9s, \u00e0 l\u2019accroissement du nombre d\u2019activit\u00e9s de la fonction RH ou encore \u00e0 la volont\u00e9 d&rsquo;uniformisation des processus internes. Tant de raisons qui ont aussi motiv\u00e9 la mise en place d\u2019une structure RH chez Audacia Group.<\/p>\n<h2 style=\"text-align: justify;\">G\u00e9rer un p\u00f4le de talents au service du groupe<\/h2>\n<p style=\"text-align: justify;\">\u00c0 travers sa vision, Audacia cherche \u00e0 cr\u00e9er un p\u00f4le de comp\u00e9tences qui r\u00e9unit des talents dispos\u00e9s \u00e0 proposer leurs savoir-faire ainsi qu\u2019un soutien quotidien aux diff\u00e9rentes entit\u00e9s du groupe. Avoir acc\u00e8s \u00e0 une structure RH commune permet ainsi aux CEO des diff\u00e9rentes soci\u00e9t\u00e9s d\u2019avoir \u00e0 leur c\u00f4t\u00e9 un partenaire strat\u00e9gique avec une vision de l\u2019ensemble et de groupe. Cela apporte ind\u00e9niablement une valeur ajout\u00e9e \u00e0 la structure g\u00e9n\u00e9rale de l\u2019entreprise.<\/p>\n<p style=\"text-align: justify;\">La fonction RH comporte deux axes: \u00e9conomique et humain. En ce qui concerne le premier, elle doit veiller \u00e0 assurer une certaine productivit\u00e9 au travail n\u00e9cessaire au bon fonctionnement de l\u2019entreprise. Pour ce qui est du deuxi\u00e8me, elle doit procurer et maintenir une certaine satisfaction professionnelle chez les employ\u00e9s. Autrement dit, une structure RH doit tenir compte du facteur humain en d\u00e9finissant la strat\u00e9gie g\u00e9n\u00e9rale de l&rsquo;entreprise. La gestion des ressources humaines englobe en fait tout le cycle de vie d\u2019un salari\u00e9. C\u2019est l\u2019humain qui cr\u00e9e de la valeur et, on l\u2019oublie parfois, c\u2019est la ressource la plus importante de toute l\u2019entreprise. L\u2019objectif primordial du service RH est donc d\u2019adapter \u00e0 l\u2019entreprise un capital humain efficace et \u00e9panoui.<\/p>\n<h2 style=\"text-align: justify;\">Des enjeux et missions divers et vari\u00e9s<\/h2>\n<p style=\"text-align: justify;\">L\u2019un des principaux enjeux de l\u2019int\u00e9gration d\u2019une structure RH \u00e0 un groupe consiste en la d\u00e9finition d\u2019une politique qui doit \u00eatre claire et calqu\u00e9e sur l\u2019identit\u00e9, les valeurs et la culture de l\u2019entreprise. Au pr\u00e9alable, il semble important de d\u00e9finir les besoins et les priorit\u00e9s puis de mettre en place une gestion administrative efficace. Cela concerne principalement la gestion des contrats de travail, l\u2019administration du personnel ainsi que la gestion des salaires. Voici les objectifs principaux de l\u2019\u00e9tablissement d\u2019une politique pour les Ressources Humaines:<\/p>\n<p style=\"text-align: justify;\">&#8211; L\u2019instauration et l\u2019unification de r\u00e8gles claires dans l\u2019organisation en pr\u00e9servant \u00e9galement les int\u00e9r\u00eats acquis des collaborateurs et collaboratrices de chaque soci\u00e9t\u00e9<br \/>\n&#8211; La conformit\u00e9 \u00e0 la l\u00e9gislation avec les contrats de travail en vigueur<br \/>\n&#8211; Le d\u00e9veloppement d\u2019un sentiment d\u2019appartenance au groupe<br \/>\n&#8211; La gestion des ressources en fonction des exigences financi\u00e8res<\/p>\n<p style=\"text-align: justify;\">Ensuite, sur le long terme, et pour b\u00e9n\u00e9ficier d\u2019une structure RH optimale qui soit en ad\u00e9quation avec la vision de l\u2019entreprise, je vais devoir faire face \u00e0 plusieurs missions qui englobent les points suivants:<\/p>\n<p style=\"text-align: justify;\"><strong>D\u00e9tecter, convaincre, d\u00e9velopper l\u2019image de l\u2019entreprise<\/strong><br \/>\nG\u00e9rer et recruter les talents, communiquer<\/p>\n<p style=\"text-align: justify;\"><strong>Mettre en place des processus propres \u00e0 la gestion des ressources humaines<\/strong><br \/>\nDigitalisation, automatisation et documentation<\/p>\n<p style=\"text-align: justify;\"><strong>Favoriser l\u2019engagement des collaborateurs et collaboratrices<\/strong><br \/>\nLes accompagner, les former, les responsabiliser et les valoriser<\/p>\n<p style=\"text-align: justify;\"><strong>Cr\u00e9er et renforcer la culture d\u2019entreprise<\/strong><br \/>\nD\u00e9velopper le sentiment d\u2019appartenance<\/p>\n<p style=\"text-align: justify;\"><strong>Rechercher des synergies en mati\u00e8re de comp\u00e9tences<\/strong><br \/>\nOrganisation du travail et cr\u00e9ation d\u2019une base de la connaissance m\u00e9tier<\/p>\n<p style=\"text-align: justify;\"><strong>Ma\u00eetriser la l\u00e9gislation<\/strong><br \/>\nMise en place d\u2019une veille l\u00e9gale et d\u2019une politique salariale<\/p>\n<h2 style=\"text-align: justify;\">Des avantages autant pour les managers que pour les employ\u00e9s<\/h2>\n<p style=\"text-align: justify;\">Au niveau du groupe, plusieurs axes viendront garantir la r\u00e9alisation de la strat\u00e9gie g\u00e9n\u00e9rale de l\u2019entreprise. Tout d\u2019abord, une harmonisation ou une simplification de la politique de r\u00e9mun\u00e9ration. Ensuite, un management des ressources humaines de proximit\u00e9 ainsi que des actions pour la parit\u00e9 au sein de l\u2019entreprise. Et finalement, une mise en place de leviers d\u2019\u00e9volution de carri\u00e8re ainsi que des actions qui visent \u00e0 d\u00e9velopper le bien-\u00eatre au travail des collaborateurs et collaboratrices.<\/p>\n<p style=\"text-align: justify;\">L\u2019int\u00e9gration d\u2019une structure RH unifi\u00e9e \u00e0 un groupe comme Audacia comporte plusieurs avantages, que ce soit pour les managers ou pour les employ\u00e9s. En ce qui concerne les premiers, ils pourront \u00eatre <span style=\"text-decoration: underline;\"><span style=\"color: #3a1def; text-decoration: underline;\"><a style=\"color: #3a1def; text-decoration: underline;\" href=\"https:\/\/www.audacia.co\/fr\/blog\/faire-partie-daudacia-nous-permet-de-beneficier-dune-infrastructure-generale-dans-plusieurs-domaines\/\" target=\"_blank\" rel=\"noopener\">lib\u00e9r\u00e9s de certaines t\u00e2ches administratives<\/a><\/span><\/span> qui faciliteront leurs activit\u00e9s manag\u00e9riales. Ils b\u00e9n\u00e9ficieront aussi d\u2019une automatisation des processus administratifs et donc, d\u2019un gain de temps. Ils profiteront finalement d\u2019une vision \u00e0 l&rsquo;\u00e9chelle de groupe\u00a0et d\u2019une digitalisation des ressources humaines. Les employ\u00e9s, eux, pourront profiter de disponibilit\u00e9, d\u2019\u00e9coute, de discr\u00e9tion, de conseils d\u2019accompagnement dans la gestion du changement, d\u2019un suivi personnel et propre \u00e0 chaque employ\u00e9 ainsi qu\u2019une approche sociale dans la relation contractuelle.<\/p>\n<p style=\"text-align: justify;\">Dans les lignes ci-dessus, j\u2019ai essay\u00e9 de pr\u00e9senter l\u2019int\u00e9gration et la vision \u00e0 long terme d\u2019une structure RH au sein d\u2019un groupe afin que cette derni\u00e8re apporte une r\u00e9elle plus-value pour le top Management ainsi que pour les collaborateurs et collaboratrices. Une fois la base construite, l\u2019acquisition puis l\u2019int\u00e9gration de nouvelles soci\u00e9t\u00e9s seront ainsi plus rapides, plus ais\u00e9es et permettront un gain de temps administratif consid\u00e9rable. Nous pourrons alors \u00e9galement nous concentrer sur le d\u00e9veloppement des comp\u00e9tences et valoriser le capital humain d\u2019<span style=\"text-decoration: underline;\"><span style=\"color: #3a1def; text-decoration: underline;\"><a style=\"color: #3a1def; text-decoration: underline;\" href=\"https:\/\/www.linkedin.com\/company\/audacia-group\/mycompany\/\" target=\"_blank\" rel=\"nofollow noopener\">Audacia<\/a><\/span><\/span>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans le cadre du d\u00e9veloppement d&rsquo;Audacia, ma principale mission consistait \u00e0 mettre en place et int\u00e9grer une structure RH au sein du groupe. Un joli challenge!<\/p>\n","protected":false},"author":17,"featured_media":2989,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[29,30],"tags":[],"class_list":["post-2994","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entreprise","category-organisation"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La structure RH au sein d&#039;un groupe: un syst\u00e8me syst\u00e9mique<\/title>\n<meta name=\"description\" content=\"Dans le cadre du d\u00e9veloppement d&#039;Audacia, ma principale mission consistait \u00e0 mettre en place et int\u00e9grer une structure RH au sein du groupe. Un joli challenge!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.audacia.co\/fr\/blog\/integration-dune-structure-rh-au-sein-dun-groupe-un-systeme-systemique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La structure RH au sein d&#039;un groupe: un syst\u00e8me syst\u00e9mique\" \/>\n<meta property=\"og:description\" content=\"Dans le cadre du d\u00e9veloppement d&#039;Audacia, ma principale mission consistait \u00e0 mettre en place et int\u00e9grer une structure RH au sein du groupe. Un joli challenge!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.audacia.co\/fr\/blog\/integration-dune-structure-rh-au-sein-dun-groupe-un-systeme-systemique\/\" \/>\n<meta property=\"og:site_name\" content=\"Audacia Group\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-23T16:01:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-22T13:29:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.audacia.co\/wp-content\/uploads\/2021\/11\/network-human-resources.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Krystel Rossmann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Krystel Rossmann\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.audacia.co\\\/fr\\\/blog\\\/integration-dune-structure-rh-au-sein-dun-groupe-un-systeme-systemique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.audacia.co\\\/fr\\\/blog\\\/integration-dune-structure-rh-au-sein-dun-groupe-un-systeme-systemique\\\/\"},\"author\":{\"name\":\"Krystel Rossmann\",\"@id\":\"https:\\\/\\\/www.audacia.co\\\/#\\\/schema\\\/person\\\/877752681a70acbdec8a5dbbbbb2ac8c\"},\"headline\":\"Int\u00e9gration d\u2019une structure RH au sein d\u2019un groupe: un syst\u00e8me syst\u00e9mique\",\"datePublished\":\"2021-11-23T16:01:23+00:00\",\"dateModified\":\"2024-10-22T13:29:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.audacia.co\\\/fr\\\/blog\\\/integration-dune-structure-rh-au-sein-dun-groupe-un-systeme-systemique\\\/\"},\"wordCount\":1062,\"publisher\":{\"@id\":\"https:\\\/\\\/www.audacia.co\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.audacia.co\\\/fr\\\/blog\\\/integration-dune-structure-rh-au-sein-dun-groupe-un-systeme-systemique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.audacia.co\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/network-human-resources.jpg\",\"articleSection\":[\"Entreprise\",\"Organisation\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.audacia.co\\\/fr\\\/blog\\\/integration-dune-structure-rh-au-sein-dun-groupe-un-systeme-systemique\\\/\",\"url\":\"https:\\\/\\\/www.audacia.co\\\/fr\\\/blog\\\/integration-dune-structure-rh-au-sein-dun-groupe-un-systeme-systemique\\\/\",\"name\":\"La structure RH au sein d'un groupe: un syst\u00e8me syst\u00e9mique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.audacia.co\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.audacia.co\\\/fr\\\/blog\\\/integration-dune-structure-rh-au-sein-dun-groupe-un-systeme-systemique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.audacia.co\\\/fr\\\/blog\\\/integration-dune-structure-rh-au-sein-dun-groupe-un-systeme-systemique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.audacia.co\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/network-human-resources.jpg\",\"datePublished\":\"2021-11-23T16:01:23+00:00\",\"dateModified\":\"2024-10-22T13:29:22+00:00\",\"description\":\"Dans le cadre du d\u00e9veloppement d'Audacia, ma principale mission consistait \u00e0 mettre en place et int\u00e9grer une structure RH au sein du groupe. Un joli challenge!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.audacia.co\\\/fr\\\/blog\\\/integration-dune-structure-rh-au-sein-dun-groupe-un-systeme-systemique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.audacia.co\\\/fr\\\/blog\\\/integration-dune-structure-rh-au-sein-dun-groupe-un-systeme-systemique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.audacia.co\\\/fr\\\/blog\\\/integration-dune-structure-rh-au-sein-dun-groupe-un-systeme-systemique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.audacia.co\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/network-human-resources.jpg\",\"contentUrl\":\"https:\\\/\\\/www.audacia.co\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/network-human-resources.jpg\",\"width\":1920,\"height\":640,\"caption\":\"hr-int\u00e9gration-groupe-audacia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.audacia.co\\\/fr\\\/blog\\\/integration-dune-structure-rh-au-sein-dun-groupe-un-systeme-systemique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.audacia.co\\\/fr\\\/audacia-group-homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Int\u00e9gration d\u2019une structure RH au sein d\u2019un groupe: un syst\u00e8me syst\u00e9mique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.audacia.co\\\/#website\",\"url\":\"https:\\\/\\\/www.audacia.co\\\/\",\"name\":\"Audacia Group\",\"description\":\"Founded in 2018 by Alexandre Bonvin, the Audacia Group brings together promising online companies in Sion (VS) and improve their profitability and customer service.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.audacia.co\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.audacia.co\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.audacia.co\\\/#organization\",\"name\":\"Audacia Group\",\"url\":\"https:\\\/\\\/www.audacia.co\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.audacia.co\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.audacia.co\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/www.audacia.co\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Audacia Group\"},\"image\":{\"@id\":\"https:\\\/\\\/www.audacia.co\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/ch.linkedin.com\\\/company\\\/audacia-group\",\"https:\\\/\\\/www.instagram.com\\\/audacia_group\\\/?hl=fr\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UChJ1W5T__cUmoj50C4489yA\\\/discussion\",\"https:\\\/\\\/open.spotify.com\\\/show\\\/73qmEvTngXLlFf4UkBLKEU\",\"https:\\\/\\\/www.tiktok.com\\\/@audacia_group\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.audacia.co\\\/#\\\/schema\\\/person\\\/877752681a70acbdec8a5dbbbbb2ac8c\",\"name\":\"Krystel Rossmann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c2889378a0e512c5aab62e9857a6ced0ce59756bdcb49db5ebd95d8b014841ef?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c2889378a0e512c5aab62e9857a6ced0ce59756bdcb49db5ebd95d8b014841ef?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c2889378a0e512c5aab62e9857a6ced0ce59756bdcb49db5ebd95d8b014841ef?s=96&d=mm&r=g\",\"caption\":\"Krystel Rossmann\"},\"description\":\"HR specialist at Audacia Group After a successful sales apprenticeship, Krystel worked in several fields and trained as an executive assistant. During those 3 years, she developed a real interest in the management of human resources and she took her career in that direction. She is currently HR specialist at Audacia Group and in the process of obtaining the federal diploma of human resources specialist.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/krystel-rossmann-0b1066112?miniProfileUrn=urnlifs_miniProfileACoAABwg7wUBJmJZi0MR0QeI7_aVQprF8mpEUa0&lipi=urnlipaged_flagship3_search_srp_alll4L8I8bjQI2TwqgoSsFxxA\"],\"url\":\"https:\\\/\\\/www.audacia.co\\\/fr\\\/blog\\\/author\\\/krossmann\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La structure RH au sein d'un groupe: un syst\u00e8me syst\u00e9mique","description":"Dans le cadre du d\u00e9veloppement d'Audacia, ma principale mission consistait \u00e0 mettre en place et int\u00e9grer une structure RH au sein du groupe. Un joli challenge!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.audacia.co\/fr\/blog\/integration-dune-structure-rh-au-sein-dun-groupe-un-systeme-systemique\/","og_locale":"fr_FR","og_type":"article","og_title":"La structure RH au sein d'un groupe: un syst\u00e8me syst\u00e9mique","og_description":"Dans le cadre du d\u00e9veloppement d'Audacia, ma principale mission consistait \u00e0 mettre en place et int\u00e9grer une structure RH au sein du groupe. Un joli challenge!","og_url":"https:\/\/www.audacia.co\/fr\/blog\/integration-dune-structure-rh-au-sein-dun-groupe-un-systeme-systemique\/","og_site_name":"Audacia Group","article_published_time":"2021-11-23T16:01:23+00:00","article_modified_time":"2024-10-22T13:29:22+00:00","og_image":[{"width":1920,"height":640,"url":"https:\/\/www.audacia.co\/wp-content\/uploads\/2021\/11\/network-human-resources.jpg","type":"image\/jpeg"}],"author":"Krystel Rossmann","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Krystel Rossmann","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.audacia.co\/fr\/blog\/integration-dune-structure-rh-au-sein-dun-groupe-un-systeme-systemique\/#article","isPartOf":{"@id":"https:\/\/www.audacia.co\/fr\/blog\/integration-dune-structure-rh-au-sein-dun-groupe-un-systeme-systemique\/"},"author":{"name":"Krystel Rossmann","@id":"https:\/\/www.audacia.co\/#\/schema\/person\/877752681a70acbdec8a5dbbbbb2ac8c"},"headline":"Int\u00e9gration d\u2019une structure RH au sein d\u2019un groupe: un syst\u00e8me syst\u00e9mique","datePublished":"2021-11-23T16:01:23+00:00","dateModified":"2024-10-22T13:29:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.audacia.co\/fr\/blog\/integration-dune-structure-rh-au-sein-dun-groupe-un-systeme-systemique\/"},"wordCount":1062,"publisher":{"@id":"https:\/\/www.audacia.co\/#organization"},"image":{"@id":"https:\/\/www.audacia.co\/fr\/blog\/integration-dune-structure-rh-au-sein-dun-groupe-un-systeme-systemique\/#primaryimage"},"thumbnailUrl":"https:\/\/www.audacia.co\/wp-content\/uploads\/2021\/11\/network-human-resources.jpg","articleSection":["Entreprise","Organisation"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.audacia.co\/fr\/blog\/integration-dune-structure-rh-au-sein-dun-groupe-un-systeme-systemique\/","url":"https:\/\/www.audacia.co\/fr\/blog\/integration-dune-structure-rh-au-sein-dun-groupe-un-systeme-systemique\/","name":"La structure RH au sein d'un groupe: un syst\u00e8me syst\u00e9mique","isPartOf":{"@id":"https:\/\/www.audacia.co\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.audacia.co\/fr\/blog\/integration-dune-structure-rh-au-sein-dun-groupe-un-systeme-systemique\/#primaryimage"},"image":{"@id":"https:\/\/www.audacia.co\/fr\/blog\/integration-dune-structure-rh-au-sein-dun-groupe-un-systeme-systemique\/#primaryimage"},"thumbnailUrl":"https:\/\/www.audacia.co\/wp-content\/uploads\/2021\/11\/network-human-resources.jpg","datePublished":"2021-11-23T16:01:23+00:00","dateModified":"2024-10-22T13:29:22+00:00","description":"Dans le cadre du d\u00e9veloppement d'Audacia, ma principale mission consistait \u00e0 mettre en place et int\u00e9grer une structure RH au sein du groupe. Un joli challenge!","breadcrumb":{"@id":"https:\/\/www.audacia.co\/fr\/blog\/integration-dune-structure-rh-au-sein-dun-groupe-un-systeme-systemique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.audacia.co\/fr\/blog\/integration-dune-structure-rh-au-sein-dun-groupe-un-systeme-systemique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.audacia.co\/fr\/blog\/integration-dune-structure-rh-au-sein-dun-groupe-un-systeme-systemique\/#primaryimage","url":"https:\/\/www.audacia.co\/wp-content\/uploads\/2021\/11\/network-human-resources.jpg","contentUrl":"https:\/\/www.audacia.co\/wp-content\/uploads\/2021\/11\/network-human-resources.jpg","width":1920,"height":640,"caption":"hr-int\u00e9gration-groupe-audacia"},{"@type":"BreadcrumbList","@id":"https:\/\/www.audacia.co\/fr\/blog\/integration-dune-structure-rh-au-sein-dun-groupe-un-systeme-systemique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.audacia.co\/fr\/audacia-group-homepage\/"},{"@type":"ListItem","position":2,"name":"Int\u00e9gration d\u2019une structure RH au sein d\u2019un groupe: un syst\u00e8me syst\u00e9mique"}]},{"@type":"WebSite","@id":"https:\/\/www.audacia.co\/#website","url":"https:\/\/www.audacia.co\/","name":"Audacia Group","description":"Founded in 2018 by Alexandre Bonvin, the Audacia Group brings together promising online companies in Sion (VS) and improve their profitability and customer service.","publisher":{"@id":"https:\/\/www.audacia.co\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.audacia.co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.audacia.co\/#organization","name":"Audacia Group","url":"https:\/\/www.audacia.co\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.audacia.co\/#\/schema\/logo\/image\/","url":"https:\/\/www.audacia.co\/wp-content\/uploads\/2020\/12\/favicon.png","contentUrl":"https:\/\/www.audacia.co\/wp-content\/uploads\/2020\/12\/favicon.png","width":512,"height":512,"caption":"Audacia Group"},"image":{"@id":"https:\/\/www.audacia.co\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/ch.linkedin.com\/company\/audacia-group","https:\/\/www.instagram.com\/audacia_group\/?hl=fr","https:\/\/www.youtube.com\/channel\/UChJ1W5T__cUmoj50C4489yA\/discussion","https:\/\/open.spotify.com\/show\/73qmEvTngXLlFf4UkBLKEU","https:\/\/www.tiktok.com\/@audacia_group"]},{"@type":"Person","@id":"https:\/\/www.audacia.co\/#\/schema\/person\/877752681a70acbdec8a5dbbbbb2ac8c","name":"Krystel Rossmann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/c2889378a0e512c5aab62e9857a6ced0ce59756bdcb49db5ebd95d8b014841ef?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c2889378a0e512c5aab62e9857a6ced0ce59756bdcb49db5ebd95d8b014841ef?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c2889378a0e512c5aab62e9857a6ced0ce59756bdcb49db5ebd95d8b014841ef?s=96&d=mm&r=g","caption":"Krystel Rossmann"},"description":"HR specialist at Audacia Group After a successful sales apprenticeship, Krystel worked in several fields and trained as an executive assistant. During those 3 years, she developed a real interest in the management of human resources and she took her career in that direction. She is currently HR specialist at Audacia Group and in the process of obtaining the federal diploma of human resources specialist.","sameAs":["https:\/\/www.linkedin.com\/in\/krystel-rossmann-0b1066112?miniProfileUrn=urnlifs_miniProfileACoAABwg7wUBJmJZi0MR0QeI7_aVQprF8mpEUa0&lipi=urnlipaged_flagship3_search_srp_alll4L8I8bjQI2TwqgoSsFxxA"],"url":"https:\/\/www.audacia.co\/fr\/blog\/author\/krossmann\/"}]}},"_links":{"self":[{"href":"https:\/\/www.audacia.co\/fr\/wp-json\/wp\/v2\/posts\/2994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.audacia.co\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.audacia.co\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.audacia.co\/fr\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.audacia.co\/fr\/wp-json\/wp\/v2\/comments?post=2994"}],"version-history":[{"count":5,"href":"https:\/\/www.audacia.co\/fr\/wp-json\/wp\/v2\/posts\/2994\/revisions"}],"predecessor-version":[{"id":6096,"href":"https:\/\/www.audacia.co\/fr\/wp-json\/wp\/v2\/posts\/2994\/revisions\/6096"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.audacia.co\/fr\/wp-json\/wp\/v2\/media\/2989"}],"wp:attachment":[{"href":"https:\/\/www.audacia.co\/fr\/wp-json\/wp\/v2\/media?parent=2994"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.audacia.co\/fr\/wp-json\/wp\/v2\/categories?post=2994"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.audacia.co\/fr\/wp-json\/wp\/v2\/tags?post=2994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}