{"id":2665,"date":"2021-08-23T08:40:10","date_gmt":"2021-08-23T08:40:10","guid":{"rendered":"https:\/\/www.audacia.co\/?p=2665"},"modified":"2022-10-31T12:29:34","modified_gmt":"2022-10-31T12:29:34","slug":"5-etapes-pour-reussir-le-lancement-de-sa-plateforme-digitale","status":"publish","type":"post","link":"https:\/\/www.audacia.co\/fr\/blog\/5-etapes-pour-reussir-le-lancement-de-sa-plateforme-digitale\/","title":{"rendered":"5 \u00e9tapes pour r\u00e9ussir le lancement de sa plateforme digitale"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Depuis une dizaine d\u2019ann\u00e9es, de nouvelles plateformes digitales de mise en relation (<em>matchmaking<\/em>) ne cessent d\u2019appara\u00eetre. Ces sites internet facilitent, comme miraculeusement, la rencontre entre une offre (le plus souvent via des professionnels qui vont payer les mises en relation) et une demande (le plus souvent via des utilisateurs qui vont b\u00e9n\u00e9ficier gratuitement des services du site internet). Or, une ann\u00e9e apr\u00e8s leur lancement, on constate qu\u2019une majorit\u00e9 de ces sites internet disparaissent.<\/p>\n<p style=\"text-align: justify;\">Chez GENILEM, nous rencontrons et conseillons beaucoup d\u2019entrepreneur\u00b7es qui se lancent dans l\u2019aventure et nous partagent les d\u00e9fis auxquels ils et elles font face. \u00c0 travers cet article, je vous propose de voir quelles sont les \u00e9tapes indispensables au lancement d\u2019une plateforme digitale et, surtout, quels en sont les facteurs cl\u00e9s de succ\u00e8s.<\/p>\n<h2 style=\"text-align: justify;\">1. Vendre avant de construire!<\/h2>\n<p style=\"text-align: justify;\">C\u2019est le pi\u00e8ge qui revient le plus souvent : les fondateurs de ces plateformes consacrent beaucoup de temps (et d\u2019argent !) \u00e0 d\u00e9velopper, d\u2019une part, une multitude de fonctionnalit\u00e9s tr\u00e8s complexes et interconnect\u00e9es, et d\u2019autre part, une image de marque tr\u00e8s co\u00fbteuse (logo, visuels, goodies, t-shirts, etc\u2026).<br \/>\nMalheureusement, au moment du \u2018go live\u2019 6 \u00e0 9 mois apr\u00e8s avoir eu l\u2019id\u00e9e, ils r\u00e9alisent soit que les utilisateurs ne recherchent pas du tout les professionnels propos\u00e9s sur la plateforme, soit qu\u2019ils ne les recherchent pas de cette mani\u00e8re-l\u00e0. Et si vous avez consacr\u00e9 tout votre budget (temps et\/ou argent) \u00e0 la construction de votre plateforme, alors vous ne pourrez pas adapter votre site internet au march\u00e9. En effet, les fondateurs de ce type de plateforme n\u2019ont souvent pas les comp\u00e9tences techniques pour adapter le code de leur site internet. C\u2019est donc une double peine car ils n\u2019ont aucune agilit\u00e9 pour adapter leur site et n\u2019ont plus que tr\u00e8s peu de ressources.<\/p>\n<p style=\"text-align: justify;\">C\u2019est d\u2019autant plus dommage car <strong>pour vendre, vous n\u2019avez pas besoin d\u2019un site internet avec toutes les fonctionnalit\u00e9s possibles et imaginables!<\/strong> Pour vendre, vous avez uniquement besoin que les gens croient que votre produit existe. Et pour cela, internet est le meilleur outil! Je m\u2019explique.<\/p>\n<p style=\"text-align: justify;\">Pour tester une plateforme de mise en relation, vous n\u2019avez absolument pas besoin d\u2019une version finie et aboutie de votre plateforme telle que vous l\u2019avez r\u00eav\u00e9e. Au contraire, un simple site internet qui fait comme si vous aviez ces fonctionnalit\u00e9s suffit amplement. L\u2019important n\u2019est pas que la premi\u00e8re version de la plateforme soit un produit fini ; elle doit uniquement servir <strong>\u00e0 valider le fait que vos utilisateurs recherchent bien les professionnels \u2018promis\u2019.<\/strong> Non sans avoir ces professionnels \u00e0 disposition bien s\u00fbr. Autrement dit, une landing page et\/ou un site statique suffit! Au moment de la mise en relation, le remplissage d\u2019un formulaire que vous traiterez \u2018\u00e0 la main\u2019 suffit amplement pour comprendre votre march\u00e9.<\/p>\n<p style=\"text-align: justify;\">L\u2019objectif ultime de cette toute premi\u00e8re phase est de <strong>valider le fait que votre id\u00e9e de d\u00e9part se concr\u00e9tise avec de vraies personnes<\/strong> qui sont pr\u00eates \u00e0 utiliser votre site internet.<\/p>\n<h2 style=\"text-align: justify;\">2. Comprendre qui sont vos 1er utilisateurs (early adopters)<\/h2>\n<p style=\"text-align: justify;\">Cette premi\u00e8re version de votre plateforme doit aussi vous servir \u00e0 comprendre qui sont vos premiers utilisateurs, souvent appel\u00e9s \u201cearly adopters\u201d, tant du c\u00f4t\u00e9 des particuliers que des professionnels.<\/p>\n<p style=\"text-align: justify;\">Une fois que votre site web en aura attir\u00e9 quelques-uns, vous devrez alors les rencontrer (physiquement ou par t\u00e9l\u00e9phone) afin de comprendre qui sont ces \u201cearly adopters\u201d et ce qu\u2019ils recherchent!<\/p>\n<p style=\"text-align: justify;\">Ce sont eux qui vont vous dire de quelles fonctionnalit\u00e9s ils ont besoin. Ce sont encore eux qui vont vous dire combien ils sont pr\u00eats \u00e0 payer pour quelle mise en relation.<\/p>\n<p>L\u2019objectif de cette \u00e9tape est <strong>d\u2019apprendre \u00e0 conna\u00eetre les diff\u00e9rentes parties prenantes de votre plateforme.<\/strong> Vous pouvez vous aider d\u2019outils, tels que <span style=\"text-decoration: underline;\"><span style=\"color: #3a1def; text-decoration: underline;\"><a style=\"color: #3a1def; text-decoration: underline;\" href=\"https:\/\/miro.com\/templates\/empathy-map\/\" target=\"_blank\" rel=\"nofollow noopener\">l\u2019empathy map<\/a><\/span><\/span>.<\/p>\n<h2 style=\"text-align: justify;\">3. Continuer \u00e0 vendre<\/h2>\n<p style=\"text-align: justify;\">M\u00eame une fois que vous aurez compris qui sont vos utilisateurs et qui sont vos clients, alors ne consacrez toujours pas trop de temps et\/ou d\u2019argent \u00e0 cr\u00e9er votre plateforme finalis\u00e9e. <strong>Continuez de vendre un maximum,<\/strong> afin, d\u2019une part, d\u2019engranger un maximum de profits et, d\u2019autre part, un maximum de donn\u00e9es. Ce n\u2019est pas grave si plusieurs fonctionnalit\u00e9s ne sont pas encore automatis\u00e9es et si vous perdez encore un peu de temps. Le plus important, c\u2019est que votre site g\u00e9n\u00e8re des transactions et un peu de <strong>chiffre d\u2019affaires<\/strong>. Continuez \u00e0 emmagasiner de l\u2019exp\u00e9rience, \u00e0 parler avec vos diff\u00e9rentes parties prenantes et \u00e0 <strong>enregistrer des donn\u00e9es!<\/strong> Les efforts fournis \u00e0 ce moment-l\u00e0 paieront plus tard.<\/p>\n<p style=\"text-align: justify;\">La r\u00e9colte et l\u2019analyse des donn\u00e9es vous permettra de d\u00e9finir votre CAC : le Customer Acquisition Cost, soit ce que vous co\u00fbte le recrutement de vos clients. Par exemple, lorsque vous d\u00e9pensez CHF 1\u2019000 dans une campagne Adwords et\/ou Google ads, combien est-ce que vous allez cr\u00e9er de conversion? Ces donn\u00e9es sont essentielles pour <strong>savoir combien vous co\u00fbte chaque nouvel utilisateur et chaque nouveau client.<\/strong><\/p>\n<p style=\"text-align: justify;\">Le principal objectif de cette phase est de <strong>comprendre davantage ce que veulent vos visiteurs<\/strong> avant de leur fabriquer pr\u00e9cis\u00e9ment ce qu\u2019ils recherchent.<\/p>\n<h2 style=\"text-align: justify;\">4. Fabriquer votre plateforme<\/h2>\n<p style=\"text-align: justify;\">C\u2019est seulement maintenant que vous pouvez commencer \u00e0 coder autre chose qu\u2019une premi\u00e8re version prototype. En effet, tant vos utilisateurs que vos clients vous ont dit ce qu\u2019ils recherchaient, quelles \u00e9taient les probl\u00e9matiques qu\u2019ils voulaient vous voir r\u00e9soudre et combien ils \u00e9taient pr\u00eats \u00e0 payer : vous allez pouvoir <strong>les satisfaire avec une version plus aboutie de votre plateforme et am\u00e9liorer la partie op\u00e9rationnelle.<\/strong> Les trois premi\u00e8res \u00e9tapes auraient \u00e9galement d\u00fb vous permettre de tester et\/ou de rencontrer les comp\u00e9tences technologiques qui vous manquaient au d\u00e9but.<\/p>\n<p style=\"text-align: justify;\">Au cours de cette quatri\u00e8me \u00e9tape, vous pouvez donc enfin am\u00e9liorer vos diff\u00e9rents indicateurs de performance et <strong>automatiser tout ce qui peut l\u2019\u00eatre<\/strong> afin de commencer \u00e0 cro\u00eetre.<\/p>\n<p style=\"text-align: justify;\">C\u2019est \u00e9galement au cours de cette p\u00e9riode, fort de la l\u00e9gitimit\u00e9 et de l\u2019exp\u00e9rience accumul\u00e9e depuis la mise en ligne de votre plateforme, que vous allez pouvoir signer des partenariats strat\u00e9giques qui vous am\u00e8neront davantage de croissance.<\/p>\n<h2 style=\"text-align: justify;\">5. Cr\u00e9er votre structure juridique<\/h2>\n<p style=\"text-align: justify;\">En parall\u00e8le \u00e0 la mise en ligne d\u2019une version am\u00e9lior\u00e9e de votre plateforme, vous pouvez enfin cr\u00e9er la <strong>bonne structure juridique<\/strong> qui vous permettra de transformer votre projet en une entreprise.<\/p>\n<p style=\"text-align: justify;\">C\u2019est aussi \u00e0 cette \u00e9tape que vous allez pouvoir mettre en place les <strong>premi\u00e8res \u2018vraies\u2019 campagnes marketing<\/strong> et commencer \u00e0 d\u00e9penser l\u2019argent que vous avez gagn\u00e9 jusque-l\u00e0. Vous ma\u00eetrisez vos indicateurs et vous pouvez prendre des d\u00e9cisions bas\u00e9es sur vos retours d\u2019exp\u00e9rience. Autrement dit, vous avez d\u00e9couvert la fameuse <span style=\"text-decoration: underline;\"><span style=\"color: #3a1def; text-decoration: underline;\"><a style=\"color: #3a1def; text-decoration: underline;\" href=\"https:\/\/blog.hubspot.com\/service\/how-to-calculate-customer-lifetime-value\" target=\"_blank\" rel=\"nofollow noopener\">\u2018life time value\u2019<\/a><\/span><\/span> (LTV) de vos utilisateurs et pouvez donc optimiser votre marketing de mani\u00e8re \u00e0 ce que votre CAC ne d\u00e9passe pas votre LTV.<\/p>\n<p style=\"text-align: justify;\">Finalement, c\u2019est le bon moment \u00e9galement pour d\u00e9l\u00e9guer certaines t\u00e2ches \u00e0 des <strong>premiers employ\u00e9s<\/strong> (\u00e0 temps partiel ou \u00e0 temps plein, en fonction de votre croissance), tout en continuant \u00e0 <strong>rester sur le terrain<\/strong>, au contact de vos utilisateurs et de vos clients pour <strong>anticiper l\u2019\u00e9volution des besoins et du march\u00e9<\/strong>.<\/p>\n<p><strong>Cyril D\u00e9l\u00e9aval<\/strong>, coach en d\u00e9veloppement d&rsquo;entreprise<\/p>\n<p style=\"text-align: justify;\"><strong>POUR ALLER PLUS LOIN<\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">&#8211; <\/span><span style=\"color: #3a1def;\"><a style=\"color: #3a1def;\" href=\"https:\/\/blog.genilem.ch\/portraits-dentrepreneurs-technis\/\" target=\"_blank\" rel=\"nofollow noopener\"><span style=\"font-weight: 400;\">Entretien avec Wiktor Bour\u00e9e, fondateur et CEO de Technis qui a brillamment su pivoter au <\/span><span style=\"font-weight: 400;\">gr\u00e9 des retours clients<\/span><\/a><\/span><span style=\"font-weight: 400;\"> (podcast GENILEM)<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8211; <\/span><span style=\"text-decoration: underline;\"><span style=\"color: #3a1def; text-decoration: underline;\"><a style=\"color: #3a1def; text-decoration: underline;\" href=\"https:\/\/blog.genilem.ch\/steve-savioz\/\" target=\"_blank\" rel=\"nofollow noopener\"><span style=\"font-weight: 400;\">Entretien avec le serial-entrepreneur, investisseur et marketer Steve Savioz : Optimiser le <\/span><span style=\"font-weight: 400;\">co\u00fbt d\u2019acquisition client<\/span><\/a><\/span><\/span><span style=\"font-weight: 400;\"> (podcast GENILEM)<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 travers cet article r\u00e9dig\u00e9 par l&rsquo;association GENILEM, d\u00e9couvrez les points essentiels \u00e0 mettre en place pour lancer sa plateforme digitale.<\/p>\n","protected":false},"author":13,"featured_media":2657,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[33,77],"tags":[],"class_list":["post-2665","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-digital","category-guest-post-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>5 \u00e9tapes pour r\u00e9ussir le lancement de sa plateforme digitale<\/title>\n<meta name=\"description\" content=\"\u00c0 travers cet article r\u00e9dig\u00e9 par l&#039;association GENILEM, d\u00e9couvrez les points essentiels \u00e0 mettre en place pour lancer sa plateforme digitale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.audacia.co\/fr\/blog\/5-etapes-pour-reussir-le-lancement-de-sa-plateforme-digitale\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5 \u00e9tapes pour r\u00e9ussir le lancement de sa plateforme digitale\" \/>\n<meta property=\"og:description\" content=\"\u00c0 travers cet article r\u00e9dig\u00e9 par l&#039;association GENILEM, d\u00e9couvrez les points essentiels \u00e0 mettre en place pour lancer sa plateforme digitale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.audacia.co\/fr\/blog\/5-etapes-pour-reussir-le-lancement-de-sa-plateforme-digitale\/\" \/>\n<meta property=\"og:site_name\" content=\"Audacia Group\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-23T08:40:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-31T12:29:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.audacia.co\/wp-content\/uploads\/2021\/08\/genilem-digital-platform.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Genilem association\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Genilem association\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.audacia.co\\\/fr\\\/blog\\\/5-etapes-pour-reussir-le-lancement-de-sa-plateforme-digitale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.audacia.co\\\/fr\\\/blog\\\/5-etapes-pour-reussir-le-lancement-de-sa-plateforme-digitale\\\/\"},\"author\":{\"name\":\"Genilem association\",\"@id\":\"https:\\\/\\\/www.audacia.co\\\/#\\\/schema\\\/person\\\/88e0bfeb3b0e85072c1f550fb2ce1bef\"},\"headline\":\"5 \u00e9tapes pour r\u00e9ussir le lancement de sa plateforme digitale\",\"datePublished\":\"2021-08-23T08:40:10+00:00\",\"dateModified\":\"2022-10-31T12:29:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.audacia.co\\\/fr\\\/blog\\\/5-etapes-pour-reussir-le-lancement-de-sa-plateforme-digitale\\\/\"},\"wordCount\":1319,\"publisher\":{\"@id\":\"https:\\\/\\\/www.audacia.co\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.audacia.co\\\/fr\\\/blog\\\/5-etapes-pour-reussir-le-lancement-de-sa-plateforme-digitale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.audacia.co\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/genilem-digital-platform.png\",\"articleSection\":[\"Digital\",\"Guest Post\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.audacia.co\\\/fr\\\/blog\\\/5-etapes-pour-reussir-le-lancement-de-sa-plateforme-digitale\\\/\",\"url\":\"https:\\\/\\\/www.audacia.co\\\/fr\\\/blog\\\/5-etapes-pour-reussir-le-lancement-de-sa-plateforme-digitale\\\/\",\"name\":\"5 \u00e9tapes pour r\u00e9ussir le lancement de sa plateforme digitale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.audacia.co\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.audacia.co\\\/fr\\\/blog\\\/5-etapes-pour-reussir-le-lancement-de-sa-plateforme-digitale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.audacia.co\\\/fr\\\/blog\\\/5-etapes-pour-reussir-le-lancement-de-sa-plateforme-digitale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.audacia.co\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/genilem-digital-platform.png\",\"datePublished\":\"2021-08-23T08:40:10+00:00\",\"dateModified\":\"2022-10-31T12:29:34+00:00\",\"description\":\"\u00c0 travers cet article r\u00e9dig\u00e9 par l'association GENILEM, d\u00e9couvrez les points essentiels \u00e0 mettre en place pour lancer sa plateforme digitale.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.audacia.co\\\/fr\\\/blog\\\/5-etapes-pour-reussir-le-lancement-de-sa-plateforme-digitale\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.audacia.co\\\/fr\\\/blog\\\/5-etapes-pour-reussir-le-lancement-de-sa-plateforme-digitale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.audacia.co\\\/fr\\\/blog\\\/5-etapes-pour-reussir-le-lancement-de-sa-plateforme-digitale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.audacia.co\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/genilem-digital-platform.png\",\"contentUrl\":\"https:\\\/\\\/www.audacia.co\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/genilem-digital-platform.png\",\"width\":1600,\"height\":900,\"caption\":\"genilem-successful-digital -platform\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.audacia.co\\\/fr\\\/blog\\\/5-etapes-pour-reussir-le-lancement-de-sa-plateforme-digitale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.audacia.co\\\/fr\\\/audacia-group-homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"5 \u00e9tapes pour r\u00e9ussir le lancement de sa plateforme digitale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.audacia.co\\\/#website\",\"url\":\"https:\\\/\\\/www.audacia.co\\\/\",\"name\":\"Audacia Group\",\"description\":\"Founded in 2018 by Alexandre Bonvin, the Audacia Group brings together promising online companies in Sion (VS) and improve their profitability and customer service.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.audacia.co\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.audacia.co\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.audacia.co\\\/#organization\",\"name\":\"Audacia Group\",\"url\":\"https:\\\/\\\/www.audacia.co\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.audacia.co\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.audacia.co\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/www.audacia.co\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Audacia Group\"},\"image\":{\"@id\":\"https:\\\/\\\/www.audacia.co\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/ch.linkedin.com\\\/company\\\/audacia-group\",\"https:\\\/\\\/www.instagram.com\\\/audacia_group\\\/?hl=fr\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UChJ1W5T__cUmoj50C4489yA\\\/discussion\",\"https:\\\/\\\/open.spotify.com\\\/show\\\/73qmEvTngXLlFf4UkBLKEU\",\"https:\\\/\\\/www.tiktok.com\\\/@audacia_group\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.audacia.co\\\/#\\\/schema\\\/person\\\/88e0bfeb3b0e85072c1f550fb2ce1bef\",\"name\":\"Genilem association\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5383ea03d0f13161fbb0b4328da14ef4a4cb87275885ad0303948ae5f4b56256?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5383ea03d0f13161fbb0b4328da14ef4a4cb87275885ad0303948ae5f4b56256?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5383ea03d0f13161fbb0b4328da14ef4a4cb87275885ad0303948ae5f4b56256?s=96&d=mm&r=g\",\"caption\":\"Genilem association\"},\"description\":\"GENILEM\u00a0is a Swiss non-profit association created in 1995. Through monitoring programs &amp; training sessions, the company aims to assist and support innovative projects &amp; businesses based in the cantons of Vaud &amp; Geneva, operating in all different sectors of business. For more than 25 years, GENILEM has been promoting the entrepreneurial world &amp; the innovation in French-speaking Switzerland.\",\"sameAs\":[\"https:\\\/\\\/genilem.ch\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/genilem\\\/\"],\"url\":\"https:\\\/\\\/www.audacia.co\\\/fr\\\/blog\\\/author\\\/genilem\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"5 \u00e9tapes pour r\u00e9ussir le lancement de sa plateforme digitale","description":"\u00c0 travers cet article r\u00e9dig\u00e9 par l'association GENILEM, d\u00e9couvrez les points essentiels \u00e0 mettre en place pour lancer sa plateforme digitale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.audacia.co\/fr\/blog\/5-etapes-pour-reussir-le-lancement-de-sa-plateforme-digitale\/","og_locale":"fr_FR","og_type":"article","og_title":"5 \u00e9tapes pour r\u00e9ussir le lancement de sa plateforme digitale","og_description":"\u00c0 travers cet article r\u00e9dig\u00e9 par l'association GENILEM, d\u00e9couvrez les points essentiels \u00e0 mettre en place pour lancer sa plateforme digitale.","og_url":"https:\/\/www.audacia.co\/fr\/blog\/5-etapes-pour-reussir-le-lancement-de-sa-plateforme-digitale\/","og_site_name":"Audacia Group","article_published_time":"2021-08-23T08:40:10+00:00","article_modified_time":"2022-10-31T12:29:34+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/www.audacia.co\/wp-content\/uploads\/2021\/08\/genilem-digital-platform.png","type":"image\/png"}],"author":"Genilem association","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Genilem association","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.audacia.co\/fr\/blog\/5-etapes-pour-reussir-le-lancement-de-sa-plateforme-digitale\/#article","isPartOf":{"@id":"https:\/\/www.audacia.co\/fr\/blog\/5-etapes-pour-reussir-le-lancement-de-sa-plateforme-digitale\/"},"author":{"name":"Genilem association","@id":"https:\/\/www.audacia.co\/#\/schema\/person\/88e0bfeb3b0e85072c1f550fb2ce1bef"},"headline":"5 \u00e9tapes pour r\u00e9ussir le lancement de sa plateforme digitale","datePublished":"2021-08-23T08:40:10+00:00","dateModified":"2022-10-31T12:29:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.audacia.co\/fr\/blog\/5-etapes-pour-reussir-le-lancement-de-sa-plateforme-digitale\/"},"wordCount":1319,"publisher":{"@id":"https:\/\/www.audacia.co\/#organization"},"image":{"@id":"https:\/\/www.audacia.co\/fr\/blog\/5-etapes-pour-reussir-le-lancement-de-sa-plateforme-digitale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.audacia.co\/wp-content\/uploads\/2021\/08\/genilem-digital-platform.png","articleSection":["Digital","Guest Post"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.audacia.co\/fr\/blog\/5-etapes-pour-reussir-le-lancement-de-sa-plateforme-digitale\/","url":"https:\/\/www.audacia.co\/fr\/blog\/5-etapes-pour-reussir-le-lancement-de-sa-plateforme-digitale\/","name":"5 \u00e9tapes pour r\u00e9ussir le lancement de sa plateforme digitale","isPartOf":{"@id":"https:\/\/www.audacia.co\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.audacia.co\/fr\/blog\/5-etapes-pour-reussir-le-lancement-de-sa-plateforme-digitale\/#primaryimage"},"image":{"@id":"https:\/\/www.audacia.co\/fr\/blog\/5-etapes-pour-reussir-le-lancement-de-sa-plateforme-digitale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.audacia.co\/wp-content\/uploads\/2021\/08\/genilem-digital-platform.png","datePublished":"2021-08-23T08:40:10+00:00","dateModified":"2022-10-31T12:29:34+00:00","description":"\u00c0 travers cet article r\u00e9dig\u00e9 par l'association GENILEM, d\u00e9couvrez les points essentiels \u00e0 mettre en place pour lancer sa plateforme digitale.","breadcrumb":{"@id":"https:\/\/www.audacia.co\/fr\/blog\/5-etapes-pour-reussir-le-lancement-de-sa-plateforme-digitale\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.audacia.co\/fr\/blog\/5-etapes-pour-reussir-le-lancement-de-sa-plateforme-digitale\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.audacia.co\/fr\/blog\/5-etapes-pour-reussir-le-lancement-de-sa-plateforme-digitale\/#primaryimage","url":"https:\/\/www.audacia.co\/wp-content\/uploads\/2021\/08\/genilem-digital-platform.png","contentUrl":"https:\/\/www.audacia.co\/wp-content\/uploads\/2021\/08\/genilem-digital-platform.png","width":1600,"height":900,"caption":"genilem-successful-digital -platform"},{"@type":"BreadcrumbList","@id":"https:\/\/www.audacia.co\/fr\/blog\/5-etapes-pour-reussir-le-lancement-de-sa-plateforme-digitale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.audacia.co\/fr\/audacia-group-homepage\/"},{"@type":"ListItem","position":2,"name":"5 \u00e9tapes pour r\u00e9ussir le lancement de sa plateforme digitale"}]},{"@type":"WebSite","@id":"https:\/\/www.audacia.co\/#website","url":"https:\/\/www.audacia.co\/","name":"Audacia Group","description":"Founded in 2018 by Alexandre Bonvin, the Audacia Group brings together promising online companies in Sion (VS) and improve their profitability and customer service.","publisher":{"@id":"https:\/\/www.audacia.co\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.audacia.co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.audacia.co\/#organization","name":"Audacia Group","url":"https:\/\/www.audacia.co\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.audacia.co\/#\/schema\/logo\/image\/","url":"https:\/\/www.audacia.co\/wp-content\/uploads\/2020\/12\/favicon.png","contentUrl":"https:\/\/www.audacia.co\/wp-content\/uploads\/2020\/12\/favicon.png","width":512,"height":512,"caption":"Audacia Group"},"image":{"@id":"https:\/\/www.audacia.co\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/ch.linkedin.com\/company\/audacia-group","https:\/\/www.instagram.com\/audacia_group\/?hl=fr","https:\/\/www.youtube.com\/channel\/UChJ1W5T__cUmoj50C4489yA\/discussion","https:\/\/open.spotify.com\/show\/73qmEvTngXLlFf4UkBLKEU","https:\/\/www.tiktok.com\/@audacia_group"]},{"@type":"Person","@id":"https:\/\/www.audacia.co\/#\/schema\/person\/88e0bfeb3b0e85072c1f550fb2ce1bef","name":"Genilem association","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5383ea03d0f13161fbb0b4328da14ef4a4cb87275885ad0303948ae5f4b56256?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5383ea03d0f13161fbb0b4328da14ef4a4cb87275885ad0303948ae5f4b56256?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5383ea03d0f13161fbb0b4328da14ef4a4cb87275885ad0303948ae5f4b56256?s=96&d=mm&r=g","caption":"Genilem association"},"description":"GENILEM\u00a0is a Swiss non-profit association created in 1995. Through monitoring programs &amp; training sessions, the company aims to assist and support innovative projects &amp; businesses based in the cantons of Vaud &amp; Geneva, operating in all different sectors of business. For more than 25 years, GENILEM has been promoting the entrepreneurial world &amp; the innovation in French-speaking Switzerland.","sameAs":["https:\/\/genilem.ch\/","https:\/\/www.linkedin.com\/company\/genilem\/"],"url":"https:\/\/www.audacia.co\/fr\/blog\/author\/genilem\/"}]}},"_links":{"self":[{"href":"https:\/\/www.audacia.co\/fr\/wp-json\/wp\/v2\/posts\/2665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.audacia.co\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.audacia.co\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.audacia.co\/fr\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.audacia.co\/fr\/wp-json\/wp\/v2\/comments?post=2665"}],"version-history":[{"count":4,"href":"https:\/\/www.audacia.co\/fr\/wp-json\/wp\/v2\/posts\/2665\/revisions"}],"predecessor-version":[{"id":4492,"href":"https:\/\/www.audacia.co\/fr\/wp-json\/wp\/v2\/posts\/2665\/revisions\/4492"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.audacia.co\/fr\/wp-json\/wp\/v2\/media\/2657"}],"wp:attachment":[{"href":"https:\/\/www.audacia.co\/fr\/wp-json\/wp\/v2\/media?parent=2665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.audacia.co\/fr\/wp-json\/wp\/v2\/categories?post=2665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.audacia.co\/fr\/wp-json\/wp\/v2\/tags?post=2665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}